{"id":224,"date":"2024-01-07T16:13:00","date_gmt":"2024-01-07T16:13:00","guid":{"rendered":"http:\/\/rabbit.wp.mountaintheme.com\/?page_id=224"},"modified":"2024-02-07T13:30:11","modified_gmt":"2024-02-07T13:30:11","slug":"low-poly-youtube-background","status":"publish","type":"page","link":"https:\/\/wordpress.mountainthemes.dev\/mountain\/low-poly-youtube-background\/","title":{"rendered":"Low-poly \u2013 Youtube background"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"224\" class=\"elementor elementor-224\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aaebd5e e-con-full e-flex e-con e-parent\" data-id=\"aaebd5e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61c3e78 elementor-widget__width-inherit elementor-widget elementor-widget-mountain-content-cover\" data-id=\"61c3e78\" data-element_type=\"widget\" data-settings=\"{&quot;aos_animation_name&quot;:&quot;none&quot;}\" data-widget_type=\"mountain-content-cover.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"cover-section\" data-animation=\"true\" data-countdown=\"true\" data-effects=\"low_poly\" data-type=\"youtube_video\">\r\n\r\n\t\t\t<div class=\"cover-content-box\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t\t<div class=\"container\">\r\n\t\t\t\t\t   <div class=\"row\">\r\n\t\t\t\t\t\t   <div class=\"col-md-12\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t   <div class=\"logo-image-box\" data-alignment=\"center\"><img decoding=\"async\" src=\"https:\/\/wordpress.mountainthemes.dev\/mountain\/wp-content\/uploads\/elementor\/thumbs\/logo-qjcyrggf8kh02wvit0eq0mt5mv43zi2jw35kle7n58.png\" title=\"logo\" alt=\"logo\" loading=\"lazy\" \/><\/div>\r\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\r\n                \r\n\t\t\t\t\t<div class=\"container\">\r\n\t\t\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t\t\t<div class=\"col-md-12\">\r\n\r\n\t\t\t\t\t\t<div class=\"inner-content-box\" data-alignment=\"center\"><h1 class=\"custom-title\">COMING SOON<\/h1>\n<p class=\"custom-text\">Our website is under construction, we are working very hard to give you the best experience with this one.\n<br>\nYou will love Mountain as much as we do. It will morph perfectly on your needs!<\/p><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t\t<div class=\"container countdown-box\" data-alignment=\"center\">\t\t\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t\t\t<div class=\"col-md-8\">\r\n\t\t\t\t\t\t\t\t<div class=\"countdown-inner-box\" data-date=\"2026\/12\/31\" data-textdays=\"days\" data-texthours=\"hours\" data-textminutes=\"minutes\" data-textseconds=\"seconds\"><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t                \r\n\t\t\t<\/div>\t\r\n\t\t\t\t\r\n\t\t\t\t\r\n                \r\n                    <div class=\"mouse-scroll\">\r\n                    <a href=\"#services\">                            <i class=\"fa fa-chevron-down\"><\/i>\r\n                        <\/a>\r\n                    <\/div>\r\n\r\n                \r\n                <div class=\"video-box\" data-mobile-image=\"https:\/\/wordpress.mountainthemes.dev\/mountain\/wp-content\/uploads\/2024\/01\/youtube-poster.png\" data-cover-image=\"https:\/\/wordpress.mountainthemes.dev\/mountain\/wp-content\/uploads\/2024\/01\/youtube-poster.png\"><div id=\"video-youtube\" data-property=\"{videoURL:'xEBC4Tn1v8A',containment:'.video-box', showControls:false, autoPlay:true, startAt:0, stopAt:0, loop:true, mute:true}\"><\/div><\/div><div id=\"effect-box\" data-color=\"rgba(255, 255, 255,\" data-opacity=\"0.3\" data-size=\"0.3\" data-density=\"100\"><canvas id=\"low-poly\"><\/canvas><\/div>\r\n\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e188d4e e-flex e-con-boxed e-con e-parent\" data-id=\"e188d4e\" data-element_type=\"container\" id=\"services\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7a34f0d e-con-full e-flex e-con e-child\" data-id=\"7a34f0d\" data-element_type=\"container\">\n\t\t\t\t<div data-aos=\"custom-fade-up\" data-aos-delay=\"100\" data-aos-once=\"true\" class=\"elementor-element elementor-element-3a621d4 elementor-widget elementor-widget-mountain-services\" data-id=\"3a621d4\" data-element_type=\"widget\" data-settings=\"{&quot;aos_animation_name&quot;:&quot;custom-fade-up&quot;}\" data-widget_type=\"mountain-services.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"services-box\"><div class=\"icon\"><i class=\"flat-icon regular fa-regular fa-laptop\" aria-hidden=\"true\" data-color=\"#16b6ea\"><\/i><\/div><h2>Inovative Ideas<\/h2><p>We don't want to conquer the cosmos, we simply want to extend the boundaries of Earth to the frontiers of the cosmos.<\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f01de5 e-con-full e-flex e-con e-child\" data-id=\"6f01de5\" data-element_type=\"container\">\n\t\t\t\t<div data-aos=\"custom-fade-up\" data-aos-delay=\"200\" data-aos-once=\"true\" class=\"elementor-element elementor-element-274fd8e elementor-widget elementor-widget-mountain-services\" data-id=\"274fd8e\" data-element_type=\"widget\" data-settings=\"{&quot;aos_animation_name&quot;:&quot;custom-fade-up&quot;}\" data-widget_type=\"mountain-services.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"services-box\"><div class=\"icon\"><i class=\"flat-icon regular fa-regular fa-code\" aria-hidden=\"true\" data-color=\"#16b6ea\"><\/i><\/div><h2>Clean code<\/h2><p>We don't want to conquer the cosmos, we simply want to extend the boundaries of Earth to the frontiers of the cosmos.<\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-51dd9e3 e-con-full e-flex e-con e-child\" data-id=\"51dd9e3\" data-element_type=\"container\">\n\t\t\t\t<div data-aos=\"custom-fade-up\" data-aos-delay=\"300\" data-aos-once=\"true\" class=\"elementor-element elementor-element-ec5aa13 elementor-widget elementor-widget-mountain-services\" data-id=\"ec5aa13\" data-element_type=\"widget\" data-settings=\"{&quot;aos_animation_name&quot;:&quot;custom-fade-up&quot;}\" data-widget_type=\"mountain-services.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"services-box\"><div class=\"icon\"><i class=\"flat-icon regular fa-regular fa-bullhorn\" aria-hidden=\"true\" data-color=\"#16b6ea\"><\/i><\/div><h2>24\/7 Support<\/h2><p>We don't want to conquer the cosmos, we simply want to extend the boundaries of Earth to the frontiers of the cosmos.<\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-84f09de e-flex e-con-boxed e-con e-parent\" data-id=\"84f09de\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-24c0027 e-con-full e-flex e-con e-child\" data-id=\"24c0027\" data-element_type=\"container\">\n\t\t\t\t<div data-aos=\"custom-fade-up\" data-aos-delay=\"100\" data-aos-once=\"true\" class=\"elementor-element elementor-element-c720b8c elementor-widget elementor-widget-mountain-title\" data-id=\"c720b8c\" data-element_type=\"widget\" data-settings=\"{&quot;aos_animation_name&quot;:&quot;custom-fade-up&quot;}\" data-widget_type=\"mountain-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-section\"><h2><i class=\"fa-solid fa-paper-plane\"><\/i>Subscribe to our newsletter<\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4bf98f5 e-con-full e-flex e-con e-child\" data-id=\"4bf98f5\" data-element_type=\"container\">\n\t\t\t\t<div data-aos=\"custom-fade-up\" data-aos-delay=\"200\" data-aos-once=\"true\" class=\"elementor-element elementor-element-343e4b7 elementor-widget elementor-widget-mountain-subscribe\" data-id=\"343e4b7\" data-element_type=\"widget\" data-settings=\"{&quot;aos_animation_name&quot;:&quot;custom-fade-up&quot;}\" data-widget_type=\"mountain-subscribe.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>(function() {\n\twindow.mc4wp = window.mc4wp || {\n\t\tlisteners: [],\n\t\tforms: {\n\t\t\ton: function(evt, cb) {\n\t\t\t\twindow.mc4wp.listeners.push(\n\t\t\t\t\t{\n\t\t\t\t\t\tevent   : evt,\n\t\t\t\t\t\tcallback: cb\n\t\t\t\t\t}\n\t\t\t\t);\n\t\t\t}\n\t\t}\n\t}\n})();\n<\/script><!-- Mailchimp for WordPress v4.10.1 - https:\/\/wordpress.org\/plugins\/mailchimp-for-wp\/ --><form id=\"mc4wp-form-1\" class=\"mc4wp-form mc4wp-form-2710\" method=\"post\" data-id=\"2710\" data-name=\"Mountain\" ><div class=\"mc4wp-form-fields\"><div class=\"subscribe-box\">\r\n  \r\n\t<input type=\"email\" name=\"EMAIL\" placeholder=\"Enter your email address\" required \/>\r\n\r\n\t<button type=\"submit\">\r\n      Submit\r\n    <\/button>\r\n\r\n<\/div><\/div><label style=\"display: none !important;\">Leave this field empty if you're human: <input type=\"text\" name=\"_mc4wp_honeypot\" value=\"\" tabindex=\"-1\" autocomplete=\"off\" \/><\/label><input type=\"hidden\" name=\"_mc4wp_timestamp\" value=\"1784095419\" \/><input type=\"hidden\" name=\"_mc4wp_form_id\" value=\"2710\" \/><input type=\"hidden\" name=\"_mc4wp_form_element_id\" value=\"mc4wp-form-1\" \/><div class=\"mc4wp-response\"><\/div><\/form><!-- \/ Mailchimp for WordPress Plugin -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d23b04e e-flex e-con-boxed e-con e-parent\" data-id=\"d23b04e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-79a51c7 e-con-full e-flex e-con e-child\" data-id=\"79a51c7\" data-element_type=\"container\">\n\t\t\t\t<div data-aos=\"custom-fade-up\" data-aos-delay=\"100\" data-aos-once=\"true\" class=\"elementor-element elementor-element-8aa4984 elementor-widget elementor-widget-mountain-title\" data-id=\"8aa4984\" data-element_type=\"widget\" data-settings=\"{&quot;aos_animation_name&quot;:&quot;custom-fade-up&quot;}\" data-widget_type=\"mountain-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-section\"><h2>Contact us<\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-edbb183 e-con-full e-flex e-con e-child\" data-id=\"edbb183\" data-element_type=\"container\">\n\t\t\t\t<div data-aos=\"custom-fade-up\" data-aos-delay=\"200\" data-aos-once=\"true\" class=\"elementor-element elementor-element-20f9128 elementor-widget elementor-widget-mountain-contact-form\" data-id=\"20f9128\" data-element_type=\"widget\" data-settings=\"{&quot;aos_animation_name&quot;:&quot;custom-fade-up&quot;}\" data-widget_type=\"mountain-contact-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3026-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"3026\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/mountain\/wp-json\/wp\/v2\/pages\/224#wpcf7-f3026-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"3026\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3026-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"contact-form\">\n\n    <input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"your-name\" \/> \n\n    <input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/> \n\n <textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Message\" name=\"your-message\"><\/textarea>\n\n <input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send message\" \/>\n\n\n\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31abe16 e-con-full e-flex e-con e-parent\" data-id=\"31abe16\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae57d9e elementor-widget elementor-widget-mountain-google-map\" data-id=\"ae57d9e\" data-element_type=\"widget\" data-settings=\"{&quot;aos_animation_name&quot;:&quot;none&quot;}\" data-widget_type=\"mountain-google-map.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div id=\"google-container\" data-latitude=\"-37.8602828\" data-longitude=\"145.079616\" data-zoom=\"10\" data-type=\"roadmap\" data-zoom-control=\"yes\" data-marker-title=\"Melbourne, Australia\" data-marker-icon=\"https:\/\/wordpress.mountainthemes.dev\/mountain\/wp-content\/uploads\/2024\/02\/icon-location.png\" data-info-window=\"\" data-style=\"[\n    {\n        &quot;elementType&quot;: &quot;labels&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;saturation&quot;: -20\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;poi&quot;,\n\t\t&quot;elementType&quot;: &quot;labels&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;visibility&quot;: &quot;off&quot;\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;road.highway&quot;,\n\t\t&quot;elementType&quot;: &quot;labels&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;visibility&quot;: &quot;off&quot;\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;road.local&quot;,\n\t\t&quot;elementType&quot;: &quot;labels.icon&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;visibility&quot;: &quot;off&quot;\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;road.arterial&quot;,\n\t\t&quot;elementType&quot;: &quot;labels.icon&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;visibility&quot;: &quot;off&quot;\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;road&quot;,\n\t\t&quot;elementType&quot;: &quot;geometry.stroke&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;visibility&quot;: &quot;off&quot;\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;transit&quot;,\n\t\t&quot;elementType&quot;: &quot;geometry.fill&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;hue&quot;: &quot;#3d4a6e&quot;\n            },\n\t\t\t{\n                &quot;visibility&quot;: &quot;on&quot;\n            },\n\t\t\t{\n                &quot;lightness&quot;: 5\n            },\n\t\t\t{\n                &quot;saturation&quot;: -20\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;poi&quot;,\n\t\t&quot;elementType&quot;: &quot;geometry.fill&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;hue&quot;: &quot;#3d4a6e&quot;\n            },\n\t\t\t{\n                &quot;visibility&quot;: &quot;on&quot;\n            },\n\t\t\t{\n                &quot;lightness&quot;: 5\n            },\n\t\t\t{\n                &quot;saturation&quot;: -20\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;poi.government&quot;,\n\t\t&quot;elementType&quot;: &quot;geometry.fill&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;hue&quot;: &quot;#3d4a6e&quot;\n            },\n\t\t\t{\n                &quot;visibility&quot;: &quot;on&quot;\n            },\n\t\t\t{\n                &quot;lightness&quot;: 5\n            },\n\t\t\t{\n                &quot;saturation&quot;: -20\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;poi.attraction&quot;,\n\t\t&quot;elementType&quot;: &quot;geometry.fill&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;hue&quot;: &quot;#3d4a6e&quot;\n            },\n\t\t\t{\n                &quot;visibility&quot;: &quot;on&quot;\n            },\n\t\t\t{\n                &quot;lightness&quot;: 5\n            },\n\t\t\t{\n                &quot;saturation&quot;: -20\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;poi.business&quot;,\n\t\t&quot;elementType&quot;: &quot;geometry.fill&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;hue&quot;: &quot;#3d4a6e&quot;\n            },\n\t\t\t{\n                &quot;visibility&quot;: &quot;on&quot;\n            },\n\t\t\t{\n                &quot;lightness&quot;: 5\n            },\n\t\t\t{\n                &quot;saturation&quot;: -20\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;transit&quot;,\n\t\t&quot;elementType&quot;: &quot;geometry.fill&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;hue&quot;: &quot;#3d4a6e&quot;\n            },\n\t\t\t{\n                &quot;visibility&quot;: &quot;on&quot;\n            },\n\t\t\t{\n                &quot;lightness&quot;: 5\n            },\n\t\t\t{\n                &quot;saturation&quot;: -20\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;transit.station&quot;,\n\t\t&quot;elementType&quot;: &quot;geometry.fill&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;hue&quot;: &quot;#3d4a6e&quot;\n            },\n\t\t\t{\n                &quot;visibility&quot;: &quot;on&quot;\n            },\n\t\t\t{\n                &quot;lightness&quot;: 5\n            },\n\t\t\t{\n                &quot;saturation&quot;: -20\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;landscape&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;hue&quot;: &quot;#3d4a6e&quot;\n            },\n\t\t\t{\n                &quot;visibility&quot;: &quot;on&quot;\n            },\n\t\t\t{\n                &quot;lightness&quot;: 5\n            },\n\t\t\t{\n                &quot;saturation&quot;: -20\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;road&quot;,\n\t\t&quot;elementType&quot;: &quot;geometry.fill&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;hue&quot;: &quot;#3d4a6e&quot;\n            },\n\t\t\t{\n                &quot;visibility&quot;: &quot;on&quot;\n            },\n\t\t\t{\n                &quot;lightness&quot;: 5\n            },\n\t\t\t{\n                &quot;saturation&quot;: -20\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;road.highway&quot;,\n\t\t&quot;elementType&quot;: &quot;geometry.fill&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;hue&quot;: &quot;#3d4a6e&quot;\n            },\n\t\t\t{\n                &quot;visibility&quot;: &quot;on&quot;\n            },\n\t\t\t{\n                &quot;lightness&quot;: 5\n            },\n\t\t\t{\n                &quot;saturation&quot;: -20\n            }\n        ]\n    },\n\t{\n        &quot;featureType&quot;: &quot;water&quot;,\n\t\t&quot;elementType&quot;: &quot;geometry&quot;,\n        &quot;stylers&quot;: [\n            {\n                &quot;hue&quot;: &quot;#3d4a6e&quot;\n            },\n\t\t\t{\n                &quot;visibility&quot;: &quot;on&quot;\n            },\n\t\t\t{\n                &quot;lightness&quot;: 5\n            },\n\t\t\t{\n                &quot;saturation&quot;: -20\n            }\n        ]\n    }\n\n]\"><\/div>\r\n\t\t\t<div class=\"contact-info-map\"><div class=\"container\"><div class=\"row\"><div class=\"col-md-12\"><div class=\"row\"><div class=\"col-md-4 contact-box\"><i class=\"fa-solid fa-location-dot\"><\/i>Melbourne, Australia<\/div><div class=\"col-md-4 contact-box\"><i class=\"fa-solid fa-phone\"><\/i>+61 3 8376 6284<\/div><div class=\"col-md-4 contact-box\"><i class=\"fa-solid fa-paper-plane\"><\/i>youremail@youremailaddress.com<\/div><\/div><\/div><\/div><\/div><\/div>\t\r\n\r\n        <div id=\"zoom-in\"><\/div><div id=\"zoom-out\"><\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>COMING SOON Our website is under construction, we are working very hard to give you the best experience with this one. You will love Mountain as much as we do. It will morph perfectly on your needs! Inovative Ideas We don&#8217;t want to conquer the cosmos, we simply want to extend the boundaries of Earth to the frontiers of the cosmos. Clean code We don&#8217;t want to conquer the cosmos,&#8230; <\/p>\n<div class=\"post-button\">\n\t\t\t   <a href=\"https:\/\/wordpress.mountainthemes.dev\/mountain\/low-poly-youtube-background\/\">Read More<\/a>\n\t\t\t<\/div>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-coming-soon-page.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-224","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/wordpress.mountainthemes.dev\/mountain\/wp-json\/wp\/v2\/pages\/224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.mountainthemes.dev\/mountain\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wordpress.mountainthemes.dev\/mountain\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.mountainthemes.dev\/mountain\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.mountainthemes.dev\/mountain\/wp-json\/wp\/v2\/comments?post=224"}],"version-history":[{"count":4,"href":"https:\/\/wordpress.mountainthemes.dev\/mountain\/wp-json\/wp\/v2\/pages\/224\/revisions"}],"predecessor-version":[{"id":6778,"href":"https:\/\/wordpress.mountainthemes.dev\/mountain\/wp-json\/wp\/v2\/pages\/224\/revisions\/6778"}],"wp:attachment":[{"href":"https:\/\/wordpress.mountainthemes.dev\/mountain\/wp-json\/wp\/v2\/media?parent=224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}